{"id":614,"date":"2016-12-17T13:20:07","date_gmt":"2016-12-17T12:20:07","guid":{"rendered":"http:\/\/www.avocat-vdb.be\/?p=614\/"},"modified":"2017-07-11T08:50:12","modified_gmt":"2017-07-11T07:50:12","slug":"assurance-vie-designation-du-beneficiaire","status":"publish","type":"post","link":"https:\/\/www.avocat-vdb.be\/fr\/assurance-vie-designation-du-beneficiaire\/","title":{"rendered":"Assurance vie &#8211; D\u00e9signation du b\u00e9n\u00e9ficiaire"},"content":{"rendered":"<p>L&rsquo;article\u00a0174 de la loi sur le contrat d&rsquo;assurance, pr\u00e9voit que\u00a0:<\/p>\n<p><em>\u00ab\u00a0Lorsque les h\u00e9ritiers l\u00e9gaux sont d\u00e9sign\u00e9s comme b\u00e9n\u00e9ficiaires sans indication de leurs noms, les prestations d&rsquo;assurance sont dues, jusqu&rsquo;\u00e0 preuve du contraire ou sauf clause contraire, \u00e0 la succession du preneur d&rsquo;assurance\u00a0\u00bb<\/em>.<\/p>\n<p>Cette disposition visait \u00e0 trancher la controverse n\u00e9e en doctrine et en jurisprudence quant aux b\u00e9n\u00e9ficiaires d&rsquo;une assurance vie lorsque le contrat pr\u00e9voit que le b\u00e9n\u00e9fice de l&rsquo;assurance reviendrait \u00ab\u00a0aux h\u00e9ritiers l\u00e9gaux\u00a0\u00bb.<\/p>\n<p>Par l&rsquo;insertion de ce nouvel article dans la L.C.A.T., le l\u00e9gislateur avait entendu attribuer \u00e0 la succession du preneur le b\u00e9n\u00e9fice d&rsquo;une telle assurance, de sorte que tout h\u00e9ritier ou l\u00e9gataire universel, voire \u00e0 titre universel, puisse dor\u00e9navant percevoir le capital assur\u00e9 puisque celui-ci revient alors dans le patrimoine successoral du d\u00e9funt afin d&rsquo;\u00eatre partag\u00e9 entre les h\u00e9ritiers l\u00e9gaux ou les l\u00e9gataires.<\/p>\n<p>Cette disposition, ins\u00e9r\u00e9e par la loi du 13\u00a0janvier 2012\u00a0[19], \u00e9tait applicable imm\u00e9diatement aux contrats souscrits apr\u00e8s son entr\u00e9e en vigueur\u00a0[20].<\/p>\n<p>Pour les contrats d&rsquo;assurance vie en cours, l&rsquo;article\u00a03 de la loi pr\u00e9cit\u00e9 avait pr\u00e9vu un d\u00e9lai transitoire de 2\u00a0ans durant lequel le preneur d&rsquo;assurance pouvait signer un avenant pour d\u00e9clarer qu&rsquo;il renon\u00e7ait \u00e0 l&rsquo;application du nouvel article\u00a0110\/1.<\/p>\n<p>Au terme de cette p\u00e9riode transitoire, \u00e0 d\u00e9faut d&rsquo;avoir sign\u00e9 le moindre avenant, l&rsquo;article\u00a0110\/1 L.C.A.T. devait s&rsquo;appliquer au contrat.<\/p>\n<p>Malheureusement, pour certains l\u00e9gataires, la p\u00e9riode transitoire n&rsquo;a pas \u00e9t\u00e9 sans difficult\u00e9.<\/p>\n<p>Ainsi, dans l&rsquo;esp\u00e8ce soumise \u00e0 la Cour constitutionnelle et ayant donn\u00e9 lieu \u00e0 l&rsquo;arr\u00eat du 3\u00a0mars 2016\u00a0[21], un homme avait souscrit une police d&rsquo;assurance et avait d\u00e9sign\u00e9, comme b\u00e9n\u00e9ficiaire, \u00ab\u00a0ses h\u00e9ritiers l\u00e9gaux\u00a0\u00bb.<\/p>\n<p>Or, il n&rsquo;avait aucuns h\u00e9ritiers l\u00e9gaux. Il avait, toutefois, r\u00e9dig\u00e9 un testament o\u00f9 il instituait un tiers comme l\u00e9gataire universel de sa succession.<\/p>\n<p>Cet homme \u00e9tant d\u00e9c\u00e9d\u00e9 durant la p\u00e9riode transitoire, donc avant l&rsquo;expiration du d\u00e9lai de deux ans pendant lequel il aurait pu renoncer \u00e0 l&rsquo;application de la loi nouvelle, la compagnie d&rsquo;assurances arguait que la disposition nouvelle ne pouvait trouver \u00e0 s&rsquo;appliquer et qu&rsquo;\u00e0 d\u00e9faut d&rsquo;h\u00e9ritiers l\u00e9gaux, il n&rsquo;existait pas de b\u00e9n\u00e9ficiaire au contrat d&rsquo;assurance.<\/p>\n<p>La Cour constitutionnelle consid\u00e8re que \u00ab\u00a0La disposition en cause a pour effet que lorsque le preneur d&rsquo;assurance d&rsquo;un contrat d&rsquo;assurance vie conclu avant le 5\u00a0mars 2012 d\u00e9c\u00e8de au cours du d\u00e9lai pr\u00e9cit\u00e9 de deux ans, la disposition contenue dans l&rsquo;article\u00a0110\/1 de la loi du 25\u00a0juin 1992 ne peut s&rsquo;appliquer\u00a0\u00bb\u00a0[22]. Apr\u00e8s une longue analyse des travaux pr\u00e9paratoires de la loi, elle d\u00e9cide qu&rsquo;en principe, les dispositions transitoires querell\u00e9es ne cr\u00e9aient pas, en soi de discrimination.<\/p>\n<p>Cependant, la Cour nuance son propos en soulignant qu&rsquo;il pouvait exister une atteinte au droit au respect des biens garanti par l&rsquo;article\u00a01er du Premier Protocole additionnel \u00e0 la Convention europ\u00e9enne des droits de l&rsquo;Homme lorsque, comme en l&rsquo;esp\u00e8ce, le l\u00e9gataire se trouvait priv\u00e9 du b\u00e9n\u00e9fice de l&rsquo;assurance vie et qu&rsquo;il n&rsquo;existait pas d&rsquo;autre b\u00e9n\u00e9ficiaire possible.<\/p>\n<p>Pour la Cour, l&rsquo;article\u00a0110\/1 est donc imm\u00e9diatement applicable au contrat d&rsquo;assurance dont le preneur ne laisse aucuns h\u00e9ritiers l\u00e9gaux, sauf \u00e0 \u00e9tablir, ce que le juge a quo doit examiner, que le preneur a entendu volontairement exclure le nouvel article\u00a0110\/1 durant la p\u00e9riode transitoire et d\u00e9nier au l\u00e9gataire le droit de percevoir le capital assur\u00e9.<\/p>\n<p>8.\u00a0R\u00e9gime matrimonial &#8211; Code Napol\u00e9on &#8211; S\u00e9paration de biens avec soci\u00e9t\u00e9 d&rsquo;acqu\u00eats &#8211; Disposition transitoire. &#8211; La Cour constitutionnelle \u00e9tait saisie de la compatibilit\u00e9 de l&rsquo;article\u00a01471 ancien du Code civil avec les articles\u00a010 et 11 de la Constitution en ce que cette disposition, applicable pour les \u00e9poux mari\u00e9 avant l&rsquo;entr\u00e9e en vigueur de la loi du 14\u00a0juillet 1976, autorisait la femme \u00e0 pr\u00e9lever, avant son \u00e9poux, les biens qu&rsquo;elle d\u00e9sire dans la communaut\u00e9\u00a0[23].<\/p>\n<p>Pour la Cour, il ne pourrait y avoir de discrimination d\u00e8s lors que l&rsquo;article\u00a01471 ancien du Code civil constituait un droit de priorit\u00e9 pour l&rsquo;\u00e9pouse.<\/p>\n<p>Cette disposition n&rsquo;avait donc pas pour cons\u00e9quence d&rsquo;avantager \u00e9conomiquement un \u00e9poux sur l&rsquo;autre.<\/p>\n<p>De plus, il \u00e9tait loisible aux \u00e9poux, depuis la r\u00e9forme de 1976, de modifier leur r\u00e9gime matrimonial afin d&rsquo;y inclure les dispositions transitoires que le l\u00e9gislateur ne leur aurait pas appliqu\u00e9es.<\/p>\n<p>\u00c0 d\u00e9faut d&rsquo;avoir d&rsquo;initiative modifi\u00e9 leur r\u00e9gime matrimonial, les \u00e9poux mari\u00e9s sous un r\u00e9gime matrimonial conventionnel ant\u00e9rieur \u00e0 la loi du 14\u00a0juillet 1976 doivent se voir appliquer toutes les dispositions de leur r\u00e9gime, en ce compris les r\u00e8gles de la liquidation auxquelles il n&rsquo;aurait pas \u00e9t\u00e9 d\u00e9rog\u00e9 par la loi \u00ab\u00a0nouvelle\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;article\u00a0174 de la loi sur le contrat d&rsquo;assurance, pr\u00e9voit que\u00a0: \u00ab\u00a0Lorsque les h\u00e9ritiers l\u00e9gaux sont d\u00e9sign\u00e9s comme b\u00e9n\u00e9ficiaires sans indication de leurs noms, les prestations d&rsquo;assurance sont dues, jusqu&rsquo;\u00e0 preuve du contraire ou sauf clause contraire, \u00e0 la succession du preneur d&rsquo;assurance\u00a0\u00bb. Cette disposition visait \u00e0 trancher la controverse n\u00e9e en doctrine et en jurisprudence [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-614","post","type-post","status-publish","format-standard","hentry","category-mediation-familiale"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/posts\/614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":1,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/posts\/614\/revisions\/643"}],"wp:attachment":[{"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.avocat-vdb.be\/fr\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}